{"id":9400,"date":"2021-10-05T17:02:27","date_gmt":"2021-10-05T15:02:27","guid":{"rendered":"https:\/\/thecamelia-bijoux.com\/?page_id=9400"},"modified":"2022-02-25T16:31:18","modified_gmt":"2022-02-25T15:31:18","slug":"collection-meknes-hiver-21-22","status":"publish","type":"page","link":"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/","title":{"rendered":"Collection Mekn\u00e8s &#8211; Hiver 21-22"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9400\" class=\"elementor elementor-9400\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ed248d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ed248d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5432751\" data-id=\"5432751\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-041643b elementor-widget elementor-widget-spacer\" data-id=\"041643b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-022944a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"022944a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1303a42\" data-id=\"1303a42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9e4215 elementor-widget elementor-widget-heading\" data-id=\"b9e4215\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 data-elementor-setting-key=\"title\" data-pen-placeholder=\"\u00c9crivez ici...\" style=\"font-style: normal;text-align: center\"><b>COLLECTION HIVER 2021<\/b><\/h2><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d31b74f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d31b74f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bee499a\" data-id=\"bee499a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bae37c elementor-widget elementor-widget-spacer\" data-id=\"8bae37c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfa69fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfa69fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5eb91c1\" data-id=\"5eb91c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-760543e elementor-widget elementor-widget-text-editor\" data-id=\"760543e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section style=\"width: 1263px; color: #01776b; font-family: Aleo, serif; left: 0px;\" data-id=\"7c8ddfb\" data-element_type=\"section\" data-settings=\"{\"><div style=\"font-size: 15px;\"><div style=\"font-size: 15px; width: 1140px;\"><div style=\"font-size: 15px; width: 1140px;\" data-id=\"6f8cf9e\" data-element_type=\"column\"><div style=\"font-size: 15px; width: 1140px;\"><div style=\"font-size: 15px; width: 1120px;\"><div style=\"font-size: 15px; color: #01776b; width: 1120px;\" data-id=\"849f562\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div style=\"font-size: 15px;\"><div style=\"font-size: 15px;\"><p style=\"font-size: 15px;\">Shooting de la collection hiver 2021-2022 : Photographe<a href=\"https:\/\/www.instagram.com\/uppperp\/\"> <u>Anna Luisa Richter<\/u><\/a>\u00a0Make up and hair\u00a0<a href=\"https:\/\/www.schoenmalerin.de\/\" target=\"_blank\" rel=\"noopener\"><u>Daniela Spranger<\/u><\/a>, Mannequins Naomi et Alex.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-90c8937 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90c8937\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-875e9ec\" data-id=\"875e9ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cacc214 elementor-widget elementor-widget-image\" data-id=\"cacc214\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"9081\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/?attachment_id=9081\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Boucles d&amp;rsquo;oreilles avant-arri\u00e8re Mekn\u00e8s, bracelet Meknassa, bracelet Chouara, bague Meknassa\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9081\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1fc0e61\" data-id=\"1fc0e61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91169ec elementor-widget elementor-widget-image\" data-id=\"91169ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-attachment-id=\"9404\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/collection-hiver-automne-2021-2022-the-camelia-bijoux\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 700D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1633515511&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Collection hiver automne 2021-2022 The Camelia bijoux\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9404\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Collection-hiver-automne-2021-2022-The-Camelia-bijoux.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-734a13d\" data-id=\"734a13d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6144a5 elementor-widget elementor-widget-image\" data-id=\"e6144a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-attachment-id=\"9405\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/manchette-meknes-bague-meknes-bague-chouara-bracelet-meknassa-bracelet-chouara-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Manchette Mekn\u00e8s, bague Mekn\u00e8s, bague Chouara, bracelet Meknassa, bracelet Chouara\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9405\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Manchette-Meknes-bague-Meknes-bague-Chouara-bracelet-Meknassa-bracelet-Chouara.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e5fa30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e5fa30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7fb6f8a\" data-id=\"7fb6f8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78e7015 elementor-widget elementor-widget-image\" data-id=\"78e7015\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9407\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/210922_lucie_bijoux_310\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?fit=1707%2C2560&amp;ssl=1\" data-orig-size=\"1707,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 700D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1632260722&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"210922_Lucie_Bijoux_310\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9407\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?w=1707&amp;ssl=1 1707w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_310-scaled.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8b25a31\" data-id=\"8b25a31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16ec9e6 elementor-widget elementor-widget-image\" data-id=\"16ec9e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9406\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/boucles-doreilles-longues-meknes-boucles-doreilles-longues-skala\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Boucles d&amp;rsquo;oreilles longues Mekn\u00e8s + Boucles d&amp;rsquo;oreilles longues Skala\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9406\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-longues-Meknes-Boucles-doreilles-longues-Skala-.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-58c7c55\" data-id=\"58c7c55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a228f19 elementor-widget elementor-widget-image\" data-id=\"a228f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9408\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/210922_lucie_bijoux_315-retouch\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?fit=1707%2C2560&amp;ssl=1\" data-orig-size=\"1707,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 700D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1632877109&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"210922_Lucie_Bijoux_315 retouch\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9408\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?w=1707&amp;ssl=1 1707w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_315-retouch-scaled.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abb7926 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abb7926\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3ec0f48\" data-id=\"3ec0f48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9d6125 elementor-widget elementor-widget-image\" data-id=\"e9d6125\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9409\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/210922_lucie_bijoux_198\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?fit=1707%2C2560&amp;ssl=1\" data-orig-size=\"1707,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 700D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1632256587&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"210922_Lucie_Bijoux_198\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9409\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?w=1707&amp;ssl=1 1707w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_198-scaled.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c9190ab\" data-id=\"c9190ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f7e023 elementor-widget elementor-widget-image\" data-id=\"0f7e023\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9411\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/210922_lucie_bijoux_185\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?fit=1707%2C2560&amp;ssl=1\" data-orig-size=\"1707,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 700D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1632255979&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"210922_Lucie_Bijoux_185\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9411\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?w=1707&amp;ssl=1 1707w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_185-scaled.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0b88c1f\" data-id=\"0b88c1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85f7ef7 elementor-widget elementor-widget-image\" data-id=\"85f7ef7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9410\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/210922_lucie_bijoux_183\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?fit=1707%2C2560&amp;ssl=1\" data-orig-size=\"1707,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 700D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1632255948&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"210922_Lucie_Bijoux_183\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9410\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?w=1707&amp;ssl=1 1707w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_183-scaled.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42c00cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42c00cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1edb34c\" data-id=\"1edb34c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7985a97 elementor-widget elementor-widget-image\" data-id=\"7985a97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9168\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/?attachment_id=9168\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bague Mekn\u00e8s, bague el-mansour, bracelet meknassa\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9168\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-el-mansour-bracelet-meknassa.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c0e3c93\" data-id=\"c0e3c93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bdd86a elementor-widget elementor-widget-image\" data-id=\"1bdd86a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9221\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/?attachment_id=9221\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Cr\u00e9oles Skala, cr\u00e9oles el-HMansour, collier Mekn\u00e8s\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9221\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Creoles-Skala-creoles-el-HMansour-collier-Meknes-1.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-02e167b\" data-id=\"02e167b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d73d680 elementor-widget elementor-widget-image\" data-id=\"d73d680\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9058\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/?attachment_id=9058\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Jonc el-hedim, bague meknassa, bague mekn\u00e8s, bague chouara\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9058\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/09\/Jonc-el-hedim-bague-meknassa-bague-meknes-bague-chouara.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a37727 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a37727\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-562e051\" data-id=\"562e051\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e65103c elementor-widget elementor-widget-image\" data-id=\"e65103c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9413\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/bague-meknes-bague-dades-bague-el-mansour-bague-menara-bague-chouara\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bague Mekn\u00e8s, bague Dad\u00e8s, bague el-Mansour, bague M\u00e9nara, bague Chouara\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9413\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-bague-Dades-bague-el-Mansour-bague-Menara-bague-Chouara.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ef82304\" data-id=\"ef82304\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2535cc elementor-widget elementor-widget-image\" data-id=\"f2535cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9414\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/bague-meknes-bague-dades-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bague Mekn\u00e8s, Bague Dad\u00e8s\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9414\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-Meknes-Bague-Dades-1.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-efc238a\" data-id=\"efc238a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84176e9 elementor-widget elementor-widget-image\" data-id=\"84176e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9412\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/bague-el-mansour-bague-menara-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bague el-Mansour, bague M\u00e9nara\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9412\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Bague-el-Mansour-bague-Menara-1.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00c2675 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00c2675\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-82bbec4\" data-id=\"82bbec4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-634df8c elementor-widget elementor-widget-image\" data-id=\"634df8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9148\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/?attachment_id=9148\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Boucles d&amp;rsquo;oreilles avant-arri\u00e8re Skala, collier Meknassa, collier M\u00e9nara, jonc Slaoui, bagues brod\u00e9es\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9148\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Skala-collier-Meknassa-collier-Menara-jonc-Slaoui-bagues-brodees.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7b2117f\" data-id=\"7b2117f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a620066 elementor-widget elementor-widget-image\" data-id=\"a620066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9149\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/?attachment_id=9149\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Colliers Meknassa + collier M\u00e9nara\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9149\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Colliers-Meknassa-collier-Menara.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7e65390\" data-id=\"7e65390\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8365114 elementor-widget elementor-widget-image\" data-id=\"8365114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9415\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/210922_lucie_bijoux_238\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?fit=1706%2C2560&amp;ssl=1\" data-orig-size=\"1706,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 700D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1632258003&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"210922_Lucie_Bijoux_238\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-9415\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?w=1706&amp;ssl=1 1706w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/210922_Lucie_Bijoux_238-scaled.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5494ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5494ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a569714\" data-id=\"a569714\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0093a3a elementor-widget elementor-widget-image\" data-id=\"0093a3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8786\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/bagues-dades-bague-menara-bague-meknes\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bagues Dad\u00e8s, bague M\u00e9nara, Bague Mekn\u00e8s\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-8786\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/10\/Bagues-Dades-bague-Menara-Bague-Meknes.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b312d9c\" data-id=\"b312d9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b00ade elementor-widget elementor-widget-image\" data-id=\"1b00ade\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8839\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/manchette-meknes-manchette-fadila-manchette-koutoubia\/\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/Manchette-Meknes-manchette-Fadila-manchette-Koutoubia.jpg?fit=1067%2C1600&amp;ssl=1\" data-orig-size=\"1067,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Manchette Mekn\u00e8s, manchette Fadila, manchette Koutoubia\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/Manchette-Meknes-manchette-Fadila-manchette-Koutoubia.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/Manchette-Meknes-manchette-Fadila-manchette-Koutoubia.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-8839\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/Manchette-Meknes-manchette-Fadila-manchette-Koutoubia.jpg?w=1067&amp;ssl=1 1067w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/Manchette-Meknes-manchette-Fadila-manchette-Koutoubia.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/Manchette-Meknes-manchette-Fadila-manchette-Koutoubia.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/Manchette-Meknes-manchette-Fadila-manchette-Koutoubia.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/Manchette-Meknes-manchette-Fadila-manchette-Koutoubia.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/Manchette-Meknes-manchette-Fadila-manchette-Koutoubia.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/Manchette-Meknes-manchette-Fadila-manchette-Koutoubia.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6767c0e\" data-id=\"6767c0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfb5412 elementor-widget elementor-widget-image\" data-id=\"dfb5412\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8852\" data-permalink=\"https:\/\/thecamelia-bijoux.com\/en\/?attachment_id=8852\" data-orig-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?fit=1600%2C2400&amp;ssl=1\" data-orig-size=\"1600,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 700D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1632866647&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Boucles d&amp;rsquo;oreilles Mendoubia\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?fit=683%2C1024&amp;ssl=1\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-8852\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2020\/02\/Boucles-doreilles-Mendoubia-1.jpg?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58cd09f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58cd09f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1e0274\" data-id=\"a1e0274\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-917a7ed elementor-widget elementor-widget-spacer\" data-id=\"917a7ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>COLLECTION HIVER 2021 Shooting de la collection hiver 2021-2022 : Photographe Anna Luisa Richter\u00a0Maquillage et coiffure\u00a0Daniela Spranger, Mannequins Naomi et Alex.<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-9400","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collection Mekn\u00e8s - Hiver 21-22 - The Camelia bijoux<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez le lookbook de la collection Mekn\u00e8s pour la saison hiver 2021-2022 avec des bijoux brod\u00e9es multicolores!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collection Mekn\u00e8s - Hiver 21-22 - The Camelia bijoux\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le lookbook de la collection Mekn\u00e8s pour la saison hiver 2021-2022 avec des bijoux brod\u00e9es multicolores!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/\" \/>\n<meta property=\"og:site_name\" content=\"The Camelia bijoux\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-25T15:31:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa-683x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/collection-meknes-hiver-21-22\\\/\",\"url\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/collection-meknes-hiver-21-22\\\/\",\"name\":\"Collection Mekn\u00e8s - Hiver 21-22 - The Camelia bijoux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/collection-meknes-hiver-21-22\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/collection-meknes-hiver-21-22\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa-683x1024.jpg\",\"datePublished\":\"2021-10-05T15:02:27+00:00\",\"dateModified\":\"2022-02-25T15:31:18+00:00\",\"description\":\"D\u00e9couvrez le lookbook de la collection Mekn\u00e8s pour la saison hiver 2021-2022 avec des bijoux brod\u00e9es multicolores!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/collection-meknes-hiver-21-22\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thecamelia-bijoux.com\\\/collection-meknes-hiver-21-22\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/collection-meknes-hiver-21-22\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa-683x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa-683x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/collection-meknes-hiver-21-22\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collection Mekn\u00e8s &#8211; Hiver 21-22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/#website\",\"url\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/\",\"name\":\"The Camelia bijoux\",\"description\":\"Bijoux brod\u00e9s \u00e0 la main inspir\u00e9s du Maroc\",\"publisher\":{\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/#organization\",\"name\":\"The Camelia bijoux\",\"url\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/thecamelia-bijoux.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/test-logo-bleu.png?fit=227%2C108&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/thecamelia-bijoux.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/test-logo-bleu.png?fit=227%2C108&ssl=1\",\"width\":227,\"height\":108,\"caption\":\"The Camelia bijoux\"},\"image\":{\"@id\":\"https:\\\/\\\/thecamelia-bijoux.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collection Mekn\u00e8s - Hiver 21-22 - The Camelia bijoux","description":"D\u00e9couvrez le lookbook de la collection Mekn\u00e8s pour la saison hiver 2021-2022 avec des bijoux brod\u00e9es multicolores!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/","og_locale":"en_GB","og_type":"article","og_title":"Collection Mekn\u00e8s - Hiver 21-22 - The Camelia bijoux","og_description":"D\u00e9couvrez le lookbook de la collection Mekn\u00e8s pour la saison hiver 2021-2022 avec des bijoux brod\u00e9es multicolores!","og_url":"https:\/\/thecamelia-bijoux.com\/en\/collection-meknes-hiver-21-22\/","og_site_name":"The Camelia bijoux","article_modified_time":"2022-02-25T15:31:18+00:00","og_image":[{"url":"https:\/\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa-683x1024.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thecamelia-bijoux.com\/collection-meknes-hiver-21-22\/","url":"https:\/\/thecamelia-bijoux.com\/collection-meknes-hiver-21-22\/","name":"Collection Mekn\u00e8s - Hiver 21-22 - The Camelia bijoux","isPartOf":{"@id":"https:\/\/thecamelia-bijoux.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thecamelia-bijoux.com\/collection-meknes-hiver-21-22\/#primaryimage"},"image":{"@id":"https:\/\/thecamelia-bijoux.com\/collection-meknes-hiver-21-22\/#primaryimage"},"thumbnailUrl":"https:\/\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa-683x1024.jpg","datePublished":"2021-10-05T15:02:27+00:00","dateModified":"2022-02-25T15:31:18+00:00","description":"D\u00e9couvrez le lookbook de la collection Mekn\u00e8s pour la saison hiver 2021-2022 avec des bijoux brod\u00e9es multicolores!","breadcrumb":{"@id":"https:\/\/thecamelia-bijoux.com\/collection-meknes-hiver-21-22\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thecamelia-bijoux.com\/collection-meknes-hiver-21-22\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/thecamelia-bijoux.com\/collection-meknes-hiver-21-22\/#primaryimage","url":"https:\/\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa-683x1024.jpg","contentUrl":"https:\/\/thecamelia-bijoux.com\/wp-content\/uploads\/2021\/10\/Boucles-doreilles-avant-arriere-Meknes-bracelet-Meknassa-bracelet-Chouara-bague-Meknassa-683x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/thecamelia-bijoux.com\/collection-meknes-hiver-21-22\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thecamelia-bijoux.com\/"},{"@type":"ListItem","position":2,"name":"Collection Mekn\u00e8s &#8211; Hiver 21-22"}]},{"@type":"WebSite","@id":"https:\/\/thecamelia-bijoux.com\/#website","url":"https:\/\/thecamelia-bijoux.com\/","name":"The Camelia bijoux","description":"Bijoux brod\u00e9s \u00e0 la main inspir\u00e9s du Maroc","publisher":{"@id":"https:\/\/thecamelia-bijoux.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thecamelia-bijoux.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/thecamelia-bijoux.com\/#organization","name":"The Camelia bijoux","url":"https:\/\/thecamelia-bijoux.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/thecamelia-bijoux.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/test-logo-bleu.png?fit=227%2C108&ssl=1","contentUrl":"https:\/\/i0.wp.com\/thecamelia-bijoux.com\/wp-content\/uploads\/2019\/02\/test-logo-bleu.png?fit=227%2C108&ssl=1","width":227,"height":108,"caption":"The Camelia bijoux"},"image":{"@id":"https:\/\/thecamelia-bijoux.com\/#\/schema\/logo\/image\/"}}]}},"jetpack_shortlink":"https:\/\/wp.me\/PaHNvJ-2rC","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thecamelia-bijoux.com\/en\/wp-json\/wp\/v2\/pages\/9400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thecamelia-bijoux.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thecamelia-bijoux.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thecamelia-bijoux.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thecamelia-bijoux.com\/en\/wp-json\/wp\/v2\/comments?post=9400"}],"version-history":[{"count":14,"href":"https:\/\/thecamelia-bijoux.com\/en\/wp-json\/wp\/v2\/pages\/9400\/revisions"}],"predecessor-version":[{"id":10299,"href":"https:\/\/thecamelia-bijoux.com\/en\/wp-json\/wp\/v2\/pages\/9400\/revisions\/10299"}],"wp:attachment":[{"href":"https:\/\/thecamelia-bijoux.com\/en\/wp-json\/wp\/v2\/media?parent=9400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}